{"id":148,"date":"2016-11-15T19:39:56","date_gmt":"2016-11-15T19:39:56","guid":{"rendered":"https:\/\/notoriginalminis.com\/en\/?post_type=envira&#038;p=148"},"modified":"2016-12-12T11:59:45","modified_gmt":"2016-12-12T11:59:45","slug":"penthesilea-infinity","status":"publish","type":"envira","link":"https:\/\/notoriginalminis.com\/en\/gallery\/penthesilea-infinity\/","title":{"rendered":"Penthesilea &#8211; Infinity"},"author":2,"featured_media":0,"template":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Penthesilea - Infinity - NotOriginalMinis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/notoriginalminis.com\/en\/gallery\/penthesilea-infinity\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Penthesilea - Infinity - NotOriginalMinis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/notoriginalminis.com\/en\/gallery\/penthesilea-infinity\/\" \/>\n<meta property=\"og:site_name\" content=\"NotOriginalMinis\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-12T11:59:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/notoriginalminis.com\/en\/gallery\/penthesilea-infinity\/\",\"url\":\"https:\/\/notoriginalminis.com\/en\/gallery\/penthesilea-infinity\/\",\"name\":\"Penthesilea - Infinity - NotOriginalMinis\",\"isPartOf\":{\"@id\":\"https:\/\/notoriginalminis.com\/en\/#website\"},\"datePublished\":\"2016-11-15T19:39:56+00:00\",\"dateModified\":\"2016-12-12T11:59:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/notoriginalminis.com\/en\/gallery\/penthesilea-infinity\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/notoriginalminis.com\/en\/gallery\/penthesilea-infinity\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/notoriginalminis.com\/en\/gallery\/penthesilea-infinity\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/notoriginalminis.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Penthesilea &#8211; Infinity\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/notoriginalminis.com\/en\/#website\",\"url\":\"https:\/\/notoriginalminis.com\/en\/\",\"name\":\"NotOriginalMinis\",\"description\":\"Creating &amp; Painting Unique Miniatures\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/notoriginalminis.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Penthesilea - Infinity - NotOriginalMinis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/notoriginalminis.com\/en\/gallery\/penthesilea-infinity\/","og_locale":"en_US","og_type":"article","og_title":"Penthesilea - Infinity - NotOriginalMinis","og_url":"https:\/\/notoriginalminis.com\/en\/gallery\/penthesilea-infinity\/","og_site_name":"NotOriginalMinis","article_modified_time":"2016-12-12T11:59:45+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/notoriginalminis.com\/en\/gallery\/penthesilea-infinity\/","url":"https:\/\/notoriginalminis.com\/en\/gallery\/penthesilea-infinity\/","name":"Penthesilea - Infinity - NotOriginalMinis","isPartOf":{"@id":"https:\/\/notoriginalminis.com\/en\/#website"},"datePublished":"2016-11-15T19:39:56+00:00","dateModified":"2016-12-12T11:59:45+00:00","breadcrumb":{"@id":"https:\/\/notoriginalminis.com\/en\/gallery\/penthesilea-infinity\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/notoriginalminis.com\/en\/gallery\/penthesilea-infinity\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/notoriginalminis.com\/en\/gallery\/penthesilea-infinity\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/notoriginalminis.com\/en\/"},{"@type":"ListItem","position":2,"name":"Penthesilea &#8211; Infinity"}]},{"@type":"WebSite","@id":"https:\/\/notoriginalminis.com\/en\/#website","url":"https:\/\/notoriginalminis.com\/en\/","name":"NotOriginalMinis","description":"Creating &amp; Painting Unique Miniatures","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/notoriginalminis.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"jetpack_sharing_enabled":true,"gallery_data":{"id":148,"config":{"type":"default","columns":"0","gallery_theme":"base","justified_gallery_theme":"normal","justified_margins":1,"justified_last_row":"nojustify","gutter":10,"margin":10,"image_size":"default","crop_width":640,"crop_height":480,"crop":0,"justified_row_height":150,"description_position":"0","description":"","random":"0","sorting_direction":"ASC","image_sizes_random":[],"dimensions":0,"isotope":1,"css_animations":1,"css_opacity":100,"lightbox_enabled":1,"lightbox_theme":"base_dark","lightbox_image_size":"default","title_display":"float","arrows":1,"arrows_position":"inside","keyboard":1,"mousewheel":1,"aspect":1,"toolbar":1,"toolbar_title":0,"toolbar_position":"top","loop":1,"lightbox_open_close_effect":"fade","effect":"fade","html5":0,"supersize":0,"thumbnails":1,"thumbnails_width":75,"thumbnails_height":50,"thumbnails_position":"bottom","mobile":1,"mobile_width":320,"mobile_height":240,"mobile_lightbox":1,"mobile_touchwipe":1,"mobile_touchwipe_close":0,"mobile_arrows":1,"mobile_toolbar":1,"mobile_thumbnails":1,"mobile_thumbnails_width":75,"mobile_thumbnails_height":50,"standalone_template":"","classes":["envira-default-gallery"],"rtl":0,"title":"Penthesilea &#8211; Infinity","slug":"penthesilea-infinity","fullscreen":0,"protection":0,"slideshow":0,"autoplay":0,"ss_speed":0,"tags":0,"tags_filter":false,"tags_position":"above","tags_all_enabled":0,"tags_all":"","tags_sorting":"","tags_manual_sorting":false,"tags_display":"","tags_scroll":0,"videos_play_icon":0,"videos_autoplay":0,"videos_playpause":0,"videos_progress":0,"videos_current":0,"videos_duration":0,"videos_volume":0,"woocommerce":0,"lightbox_woocommerce":0,"deeplinking":0,"native_gallery_override":0,"zoom":0,"zoom_hover":0,"zoom_position":"upper-left","zoom_type":"basic","zoom_effect":"no-effect","zoom_lens_shape":"round","zoom_window_size":"small","zoom_tint_color":"","zoom_tint_color_opacity":"50","zoom_mousewheel":0,"mobile_zoom":0,"layout":"automatic"},"gallery":[{"status":"active","src":"https:\/\/notoriginalminis.com\/en\/wp-content\/uploads\/sites\/2\/2016\/11\/Penthesilea-infinity-bike-5-960x1024.jpg","title":"Penthesilea-infinity-bike-5","link":"https:\/\/notoriginalminis.com\/en\/wp-content\/uploads\/sites\/2\/2016\/11\/Penthesilea-infinity-bike-5.jpg","alt":"","caption":"","thumb":"https:\/\/notoriginalminis.com\/en\/wp-content\/uploads\/sites\/2\/2016\/11\/Penthesilea-infinity-bike-5-150x100_c.jpg","tags":[],"mobile_thumb":"https:\/\/notoriginalminis.com\/en\/wp-content\/uploads\/sites\/2\/2016\/11\/Penthesilea-infinity-bike-5-150x100_c.jpg","id":285,"height":1024,"width":960},{"status":"active","src":"https:\/\/notoriginalminis.com\/en\/wp-content\/uploads\/sites\/2\/2016\/11\/Penthesilea-infinity-bike-4-1015x1024.jpg","title":"Penthesilea-infinity-bike-4","link":"https:\/\/notoriginalminis.com\/en\/wp-content\/uploads\/sites\/2\/2016\/11\/Penthesilea-infinity-bike-4.jpg","alt":"","caption":"","thumb":"https:\/\/notoriginalminis.com\/en\/wp-content\/uploads\/sites\/2\/2016\/11\/Penthesilea-infinity-bike-4-150x100_c.jpg","tags":[],"mobile_thumb":"https:\/\/notoriginalminis.com\/en\/wp-content\/uploads\/sites\/2\/2016\/11\/Penthesilea-infinity-bike-4-150x100_c.jpg","id":284,"height":1024,"width":1015},{"status":"active","src":"https:\/\/notoriginalminis.com\/en\/wp-content\/uploads\/sites\/2\/2016\/11\/Penthesilea-infinity-bike-3-1001x1024.jpg","title":"Penthesilea-infinity-bike-3","link":"https:\/\/notoriginalminis.com\/en\/wp-content\/uploads\/sites\/2\/2016\/11\/Penthesilea-infinity-bike-3.jpg","alt":"","caption":"","thumb":"https:\/\/notoriginalminis.com\/en\/wp-content\/uploads\/sites\/2\/2016\/11\/Penthesilea-infinity-bike-3-150x100_c.jpg","tags":[],"mobile_thumb":"https:\/\/notoriginalminis.com\/en\/wp-content\/uploads\/sites\/2\/2016\/11\/Penthesilea-infinity-bike-3-150x100_c.jpg","id":283,"height":1024,"width":1001},{"status":"active","src":"https:\/\/notoriginalminis.com\/en\/wp-content\/uploads\/sites\/2\/2016\/11\/Penthesilea-infinity-bike-2-966x1024.jpg","title":"Penthesilea-infinity-bike-2","link":"https:\/\/notoriginalminis.com\/en\/wp-content\/uploads\/sites\/2\/2016\/11\/Penthesilea-infinity-bike-2.jpg","alt":"","caption":"","thumb":"https:\/\/notoriginalminis.com\/en\/wp-content\/uploads\/sites\/2\/2016\/11\/Penthesilea-infinity-bike-2-150x100_c.jpg","tags":[],"mobile_thumb":"https:\/\/notoriginalminis.com\/en\/wp-content\/uploads\/sites\/2\/2016\/11\/Penthesilea-infinity-bike-2-150x100_c.jpg","id":282,"height":1024,"width":966},{"status":"active","src":"https:\/\/notoriginalminis.com\/en\/wp-content\/uploads\/sites\/2\/2016\/11\/Penthesilea-infinity-bike-1.jpg","title":"Penthesilea-infinity-bike-1","link":"https:\/\/notoriginalminis.com\/en\/wp-content\/uploads\/sites\/2\/2016\/11\/Penthesilea-infinity-bike-1.jpg","alt":"","caption":"","thumb":"https:\/\/notoriginalminis.com\/en\/wp-content\/uploads\/sites\/2\/2016\/11\/Penthesilea-infinity-bike-1-150x100_c.jpg","tags":[],"mobile_thumb":"https:\/\/notoriginalminis.com\/en\/wp-content\/uploads\/sites\/2\/2016\/11\/Penthesilea-infinity-bike-1-150x100_c.jpg","id":281,"height":615,"width":568}]},"_links":{"self":[{"href":"https:\/\/notoriginalminis.com\/en\/wp-json\/wp\/v2\/envira-gallery\/148"}],"collection":[{"href":"https:\/\/notoriginalminis.com\/en\/wp-json\/wp\/v2\/envira-gallery"}],"about":[{"href":"https:\/\/notoriginalminis.com\/en\/wp-json\/wp\/v2\/types\/envira"}],"author":[{"embeddable":true,"href":"https:\/\/notoriginalminis.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/notoriginalminis.com\/en\/wp-json\/wp\/v2\/media?parent=148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}